{"id":16,"count":32,"description":"","link":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/","name":"Demo Garden","slug":"demo-garden","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Demo Garden Archives - Chilton County Master Gardeners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demo Garden Archives - Chilton County Master Gardeners\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/\" \/>\n<meta property=\"og:site_name\" content=\"Chilton County Master Gardeners\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/\",\"url\":\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/\",\"name\":\"Demo Garden Archives - Chilton County Master Gardeners\",\"isPartOf\":{\"@id\":\"http:\/\/mg.aces.edu\/chilton\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/mg.aces.edu\/chilton\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demo Garden\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/mg.aces.edu\/chilton\/#website\",\"url\":\"http:\/\/mg.aces.edu\/chilton\/\",\"name\":\"Chilton County Master Gardeners\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/mg.aces.edu\/chilton\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demo Garden Archives - Chilton County Master Gardeners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/","og_locale":"en_US","og_type":"article","og_title":"Demo Garden Archives - Chilton County Master Gardeners","og_url":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/","og_site_name":"Chilton County Master Gardeners","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/","url":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/","name":"Demo Garden Archives - Chilton County Master Gardeners","isPartOf":{"@id":"http:\/\/mg.aces.edu\/chilton\/#website"},"breadcrumb":{"@id":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/mg.aces.edu\/chilton\/category\/demo-garden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/mg.aces.edu\/chilton\/"},{"@type":"ListItem","position":2,"name":"Demo Garden"}]},{"@type":"WebSite","@id":"http:\/\/mg.aces.edu\/chilton\/#website","url":"http:\/\/mg.aces.edu\/chilton\/","name":"Chilton County Master Gardeners","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/mg.aces.edu\/chilton\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/mg.aces.edu\/chilton\/wp-json\/wp\/v2\/categories\/16"}],"collection":[{"href":"http:\/\/mg.aces.edu\/chilton\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/mg.aces.edu\/chilton\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/mg.aces.edu\/chilton\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}